{"id":811,"date":"2026-02-26T18:49:39","date_gmt":"2026-02-26T18:49:39","guid":{"rendered":"https:\/\/gabinetejuridico.co\/?p=811"},"modified":"2026-02-26T18:49:40","modified_gmt":"2026-02-26T18:49:40","slug":"smlmv","status":"publish","type":"post","link":"https:\/\/gabinetejuridico.co\/index.php\/2026\/02\/26\/smlmv\/","title":{"rendered":"SMLMV"},"content":{"rendered":"\n<p class=\"has-text-align-center has-x-large-font-size\">SMLMV<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2026\/02\/SM-1024x576.png\" alt=\"\" class=\"wp-image-813\" srcset=\"https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2026\/02\/SM-1024x576.png 1024w, https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2026\/02\/SM-300x169.png 300w, https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2026\/02\/SM-768x432.png 768w, https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2026\/02\/SM-1536x864.png 1536w, https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2026\/02\/SM.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<p style=\"background-color:#ededed;\" class=\"wp-elements-566b923dbd8517c4b49369186c4eee3a wp-block-site-tagline has-text-color has-black-color has-background\">Autor Dr. Ismael Guerrero Mill\u00e1n &#8211; Dir. Jur\u00eddico<\/p>\n\n\n<p class=\"has-medium-font-size\">Nos encontramos en una situaci\u00f3n in\u00e9dita, la que se da como producto de la improvisaci\u00f3n por parte del Gobierno Nacional, al expedir el decreto 1469 de 2025, por el que fij\u00f3 el salario m\u00ednimo para el a\u00f1o 2026, ante la falta de concertaci\u00f3n en la comisi\u00f3n tripartita.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">As\u00ed pues, ten\u00edamos un salario m\u00ednimo de $1.423.500 y con el incremento del 23,7%, qued\u00f3 en $1.750.905, a lo que se debe sumar el auxilio de transporte de $249.095, para un total de $2.000.000.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Claro que no es este \u00faltimo un valor \u00fanico para el empleador, porque la sumatoria de la salud, pensi\u00f3n, ARL, caja de compensaci\u00f3n, primas cesant\u00edas, intereses a al cesant\u00edas y vacaciones al salario; totalizan $2.864.324,19 mensuales.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Ante esta situaci\u00f3n, se demand\u00f3 el decreto ante el Consejo de Estado, con la petici\u00f3n de suspensi\u00f3n provisional.<\/p>\n\n\n\n<p class=\"has-background has-medium-font-size\" style=\"background-color:#e1e1e1\">Asignado al Consejero Juan Carlos Morales, por auto del 13 de febrero de 2026, se decret\u00f3 la suspensi\u00f3n provisional, aduciendo, que aunque el gobierno \u201cdesarrollo de manera extensa el concepto de salario vital como referente\u201d para el porcentaje decretado, no pod\u00eda excluir los par\u00e1metros que da la ley 278 en su Art.- 8 y que fueron ratificados y ampliados en la sentencia de constitucionalidad 815 de 2019; diciendo que no se explic\u00f3 articuladamente como encadenar los par\u00e1metros, individual o conjuntamente en el porcentaje del 23,7%; o sea que <strong><u>NO DEMOSTR\u00d3 QUE LAS TASAS DE INFLACION, PRODUCTIVIDAD Y PIB INFLUYERON EN LA OPERACI\u00d3N MATEM\u00c1TICA<\/u><\/strong> (esta es tarea para Min Trabajo \u2013 Antonio Sanguino, quien ha demostrado sus profundos conocimientos sobre Keynes).<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\">Ahora, <strong>\u00bfQu\u00e9 criterios tuvo con Consejo de Estado para decretar la suspensi\u00f3n provisional del decreto 1469 del 29 de diciembre de 2025?<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Previamente adujo:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"has-medium-font-size\">Si en sede de medida cautelar se examina si del decreto se desprende infracci\u00f3n al Art.- 8 de la ley 278.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">La sentencia 815 de 1999 dice que los factores (inflaci\u00f3n del a\u00f1o siguiente, inflaci\u00f3n causada, productividad acordada, contribuci\u00f3n de los salarios al ingreso nacional en el incremento del PIB) deben ser incluido, medidos y evaluados por el gobierno al expedir el respectivo decreto.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">La debida y suficiente motivaci\u00f3n del acto administrativo es requisito sustancial y en este momento procesal, en sede de cautela no es un an\u00e1lisis exhaustivo propio del fallo; se incorpor\u00f3 el criterio de salario vital con base en los conceptos 95 y 131 de la OIT (no vinculantes).<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Dice el Consejo que del decreto no se desprende un racionamiento que de la incidencia de cada par\u00e1metro dado por la ley 278, solamente son enunciados \u201cpero no integrados\u201d, d\u00e1ndose una incoherencia en la motivaci\u00f3n; en contrav\u00eda de la jurisprudencia del mismo Consejo de Estado, que dice que los par\u00e1metros no son criterios orientadores, si no la carga motiva para la fijaci\u00f3n del salario m\u00ednimo unilateralmente.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Existe un desconocimiento del marco normativo, o sea el Min Trabajo, aleg\u00f3 que el decreto tiene una motivaci\u00f3n complementada por una memoria justificativa incorporada como anexo t\u00e9cnico para el decreto, este es un insumo previo y aunque el ministerio aduce que los par\u00e1metros fueron \u201cvalorados\u201d y \u201cponderado\u201d no reproduce estas afirmaciones en el decreto 1469 de 2025.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Importante es ver, en el auto de Consejero Morales que \u00e9ste aduce, que al no estar integradas las variables del Art.- 8 de la ley 278, ni cuantificadas en la operaci\u00f3n que llev\u00f3 al 23,7%, entonces, mal se puede llegar a este percentil por arte de birlibirloque.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Existe entonces una incoherencia en la motivaci\u00f3n, ya que mientras se dice que el salario vital no sustituye los mecanismos de fijaci\u00f3n del salario m\u00ednimo; en la pr\u00e1ctica dicho concepto se vuelve el eje central desconociendo que los par\u00e1metros de la ley 278 son la carga motiva necesaria para fijar por decreto el salario m\u00ednimo.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Se ve en esta etapa cautelar que existe un desconocimiento normativo sobre lo dictado por el Art.- 8 de la ley 278 por lo que resulta procedente el decreto de la cautela.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">La afirmaci\u00f3n del gobierno, respecto a que la ley \u201cno establece una f\u00f3rmula matem\u00e1tica obligatoria\u201d, no habilita para establecer un esquema alternativo.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">La facultad invocada debe ejercerse dentro de los m\u00e1rgenes del ordenamiento jur\u00eddico.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Ordena el consejero que las entidades demandadas dentro de los 8 d\u00edas calendario siguientes a la notificaci\u00f3n expidan un decreto por el que fije el porcentaje por el que transitoriamente se incrementa el SMLMV para 2026, en tanto se dicta sentencia. &nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n<\/ol>\n\n\n\n<p class=\"has-medium-font-size\">A esto di\u00f3 cumplimiento el gobierno nacional por el decreto 159 de 2026.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">El comentario a este ultimo decreto, lo haremos despu\u00e9s de entender las explicaciones econ\u00f3micas del Min Trabajo sobre Keynes.<\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#fb9b56\"><strong>IMPROVISACI\u00d3N= AN\u00c1LISIS<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>EGU SUNT QUESUM<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SMLMV Nos encontramos en una situaci\u00f3n in\u00e9dita, la que se da como producto de la improvisaci\u00f3n por parte del Gobierno Nacional, al expedir el decreto 1469 de 2025, por el que fij\u00f3 el salario m\u00ednimo para el a\u00f1o 2026, ante la falta de concertaci\u00f3n en la comisi\u00f3n tripartita. As\u00ed pues, ten\u00edamos un salario m\u00ednimo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"categories":[5],"tags":[59,70],"class_list":["post-811","post","type-post","status-publish","format-standard","hentry","category-rama-judicial","tag-consejo-de-estado","tag-salario-minimo"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts\/811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/comments?post=811"}],"version-history":[{"count":6,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts\/811\/revisions"}],"predecessor-version":[{"id":819,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts\/811\/revisions\/819"}],"wp:attachment":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/media?parent=811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/categories?post=811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/tags?post=811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}