{"id":726,"date":"2024-05-14T21:00:40","date_gmt":"2024-05-14T21:00:40","guid":{"rendered":"https:\/\/gabinetejuridico.co\/?p=726"},"modified":"2024-05-14T20:44:24","modified_gmt":"2024-05-14T20:44:24","slug":"incapacitante","status":"publish","type":"post","link":"https:\/\/gabinetejuridico.co\/index.php\/2024\/05\/14\/incapacitante\/","title":{"rendered":"INCAPACITANTE"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Escrito por Ismael Guerrero Mil\u00e1n &#8211; Dir. Gabinete Jur\u00eddico. <\/h4>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<ul class=\"wp-block-social-links is-content-justification-center is-layout-flex wp-container-core-social-links-is-layout-16018d1d wp-block-social-links-is-layout-flex\">\n\n\n\n\n\n<\/ul>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-left has-medium-font-size\">De nuestro entorno, cualquiera que \u00e9ste sea, hemos tenido cercan\u00eda con alguna mujer, que entre su afecci\u00f3n tenga \u201cdolor bajito\u201d y que \u00e9ste sea una de las demostraciones de dolencias, que la lleven a no poder ejercer cabalmente sus actividades laborales (a m\u00e1s de otros s\u00edntomas).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">De hecho, esta situaci\u00f3n m\u00e1s que com\u00fan, llev\u00f3 a que se expidiera la ley 2353 (ley de endometrosis); pero, bueno es adentrarnos un poco en el tema, seg\u00fan cifras de la Asociaci\u00f3n Colombiana de Endometrosis e Infertilidad, hay 3,5 millones de mujeres diagnosticadas con endometrosis en Colombia y en el mundo 170 millones.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u00bfQu\u00e9 otros s\u00edntomas tiene esta enfermedad? (Es la presencia del tejido endometrial de manera anormal en la cavidad abdominal), incluye dolor en los ovarios, en las trompas de Falopio y hasta los intestinos, esto llev\u00f3 a que se presentar\u00e1 un proyecto de ley, por los Representantes Andr\u00e9s Toro, \u00c1ngela Mar\u00eda Robledo y las senadora Ang\u00e9lica Lozano y Esperanza Andrade, entre otros, el que se convirti\u00f3 en la ley 2358 y en el que se busca dar cobertura a mujeres que sufren dicha enfermedad y da \u00f3rdenes al estado \u201cpara hacer pol\u00edticas para acceso y estabilidad en el empleo\u201d.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">A m\u00e1s de lo anterior se tiene por parte de quienes padecen esta enfermedad: dolor en la zona p\u00e9lvica, dolor incapacitante en las menstruaciones, dolor durante las relaciones sexuales, s\u00edntomas &nbsp;anormales al orinar y defecar, fatiga cr\u00f3nica y cansancio constante.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><\/summary>\n<p><\/p>\n<\/details>\n\n\n\n<p>Pero, \u00bfA qu\u00e9 tanta ch\u00e1chara con terminolog\u00eda m\u00e9dica, si este es un sitio de abogados y para abogados?, nos lleva el tema a la sentencia T-448 \/2023, mediante la que la Corte Constitucional, Sala Primera de Revisi\u00f3n, en dicha acci\u00f3n de Dennis P\u00e9rez, (nombre sustituido de la accionante por la anonimizaci\u00f3n de nombres en providencias disponibles de acceso p\u00fablico), contra una empresa de servicios temporales y la empresa usuario, se ampar\u00f3 el derecho a la estabilidad reforzada por salud y a la protecci\u00f3n de la persona en situaci\u00f3n de debilidad manifiesta por salud por endometrosis, y declara ineficaz el despido, por haberlo sido en medio del tratamiento y sin autorizaci\u00f3n de Ministerio de Trabajo. Ac\u00e1, es impajaritable, llamar la atenci\u00f3n sobre el caso puntualmente, en cuanto a la actividad desplegada por la temporal que al verse ante las solicitudes de la petente, decidi\u00f3 desvincularla (oportunamente les hab\u00eda comunicado el diagnostico de endometrosis); y que el Tribunal de cierre, ampar\u00f3 el derecho de la se\u00f1ora Dennis P\u00e9rez, declarando ineficaz el despido, con las consecuencias de:<\/p>\n\n\n\n<p class=\"has-medium-font-size\">1. Reintegro.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">2. Pago de los salarios y prestaciones desde la terminaci\u00f3n del contrato y la indemnizaci\u00f3n de 180 d\u00edas de salario., contenido en la ley 361 de 1997.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Nos debemos centrar en la tipificaci\u00f3n de la causal que se invoca para el finiquito convencional.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">EGU SUM QUESUM. \u00a1Cuidado abogados de empleadores!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escrito por Ismael Guerrero Mil\u00e1n &#8211; Dir. Gabinete Jur\u00eddico. De nuestro entorno, cualquiera que \u00e9ste sea, hemos tenido cercan\u00eda con alguna mujer, que entre su afecci\u00f3n tenga \u201cdolor bajito\u201d y que \u00e9ste sea una de las demostraciones de dolencias, que la lleven a no poder ejercer cabalmente sus actividades laborales (a m\u00e1s de otros s\u00edntomas). [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"categories":[6,8,5,7],"tags":[50,49,48,51,46],"class_list":["post-726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corte-suprema-de-justicia","category-derecho","category-rama-judicial","category-tutelas","tag-contrato-laboral","tag-corte-constitucional","tag-endometriosis","tag-ley-2353","tag-t-448-2023"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts\/726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/comments?post=726"}],"version-history":[{"count":10,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts\/726\/revisions"}],"predecessor-version":[{"id":736,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts\/726\/revisions\/736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/media\/728"}],"wp:attachment":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/media?parent=726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/categories?post=726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/tags?post=726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}