{"id":696,"date":"2024-04-12T16:11:12","date_gmt":"2024-04-12T16:11:12","guid":{"rendered":"https:\/\/gabinetejuridico.co\/?p=696"},"modified":"2024-04-12T21:00:09","modified_gmt":"2024-04-12T21:00:09","slug":"mancuso-bisagra","status":"publish","type":"post","link":"https:\/\/gabinetejuridico.co\/index.php\/2024\/04\/12\/mancuso-bisagra\/","title":{"rendered":"MANCUSO BISAGRA"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2024\/04\/MANCUSOO-01-1024x576.png\" alt=\"Por medio de la Res. 244 de 2023, el Presidente GUSTAVO PETRO, design\u00f3 a SALVATORE MANCUSO G\u00d3MEZ como gestor de paz, para que: \u201c\u2026contribuya con su conocimiento y experiencia al dise\u00f1o de procesos de desarme colectivos\u2026\u201d\nEl gestor de paz queda bajo justicia y paz, la Jurisdicci\u00f3n Especial para la Paz y la Fiscal\u00eda General de la Naci\u00f3n. \n\" class=\"wp-image-699\" srcset=\"https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2024\/04\/MANCUSOO-01-1024x576.png 1024w, https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2024\/04\/MANCUSOO-01-300x169.png 300w, https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2024\/04\/MANCUSOO-01-768x432.png 768w, https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2024\/04\/MANCUSOO-01-1536x864.png 1536w, https:\/\/gabinetejuridico.co\/wp-content\/uploads\/2024\/04\/MANCUSOO-01-2048x1152.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4c8f938a61fffa88084b160cfa541871\"><strong>Escrito por: Ismael Enrique Guerrero &#8211; Dir. Gabinete Jur\u00eddico. <\/strong><\/p>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">MANCUSO BISAGRA<\/h1>\n\n\n\n<p class=\"has-medium-font-size\">Observar el discurrir de lo que ha sido el conflicto armado en Colombia, desde los estudios del maestro EDUARDO UMA\u00d1A LUNA, ORLANDO FALS BORDA y GERM\u00c1N GUZM\u00c1N, el 9 de abril de 1948, la guerrilla, la reacci\u00f3n paramilitar, AUC y ACC y ver ahora, las resultas de lo que ocurre con SALVATORE MANCUSO G\u00d3MEZ, nos lleva a tener que observar detenidamente el momento actual de \u00e9ste, la JEP acept\u00f3 como compareciente a MANCUSO G\u00d3MEZ, que tambi\u00e9n fue nombrado por el presidente como \u201cGestor de paz\u201d, a m\u00e1s de tenerlo la JURISDICCI\u00d3N ESPECIAL PARA LA PAZ &#8211; JEP como miembro \u201cfuncional y material entre los a\u00f1os 1989 y 2004\u201d, es lo determinado por la JEP en la resoluci\u00f3n por la cual lo acepta. (Recordemos que SALVATORE MANCUSO, tiene investigaciones en la Fiscal\u00eda General de la Naci\u00f3n por lavado de activos).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u00a1No es ni ser\u00e1 f\u00e1cil de entender, lo que ocurre!<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-medium-font-size\">Por medio de la Res. 244 de 2023, el Presidente GUSTAVO PETRO, design\u00f3 a SALVATORE MANCUSO G\u00d3MEZ como gestor de paz, para que: \u201c\u2026contribuya con su conocimiento y experiencia al dise\u00f1o de procesos de desarme colectivos\u2026\u201d<\/p>\n\n\n\n<p class=\"has-medium-font-size\">El gestor de paz queda bajo justicia y paz, la Jurisdicci\u00f3n Especial para la Paz y la Fiscal\u00eda General de la Naci\u00f3n.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-medium-font-size\">Bueno, pues, veamos, si MANCUSO en los a\u00f1os mencionados, ten\u00eda la capacidad para \u201cunir los hilos entre los militares, paramilitares y otros agentes del estado, empresarios y pol\u00edticos para construir el enganche de una estructura paramilitar\u201d, quiere ello decir, que el exjefe paramilitar, era un \u201cs\u00faper poder\u201d, dentro de la estructura de las AUC, por encima del que se crey\u00f3 era el jefe: Carlos Casta\u00f1o.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u00bfQu\u00e9 caminos ha tenido esto? En mayo de 2023, la Sala de Definici\u00f3n de situaciones jur\u00eddicas, en audiencia \u00fanica de aporte a la verdad, efectu\u00f3 interrogatorio a MANCUSO G\u00d3MEZ, sobre varios puntos: las Convivir, operaciones conjuntas, acuerdos entre fuerza p\u00fablica y paramilitares, su relaci\u00f3n como puente entre paramilitares, agentes del estado y empresarios del 1989 a 2004 (recordemos que fue extraditado en 2008).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Si el compromiso en justicia y paz, era decir la verdad, \u201ctoda\u201d, entonces la \u201cverdad\u201d, que dice ahora \u00bfes diferente?, en justicia y paz no dijo \u00bftoda la verdad?, \u00a1esto tendr\u00eda la consecuencia de perder los beneficios!<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u00bfQu\u00e9 implica la decisi\u00f3n de la Sala de definici\u00f3n de situaciones jur\u00eddicas?, veamos:<\/p>\n\n\n\n<p class=\"has-medium-font-size\">1. El sometimiento de MANCUSO es por hechos entre 1989 y 2004, \u201cBisagra\u201d (incorporaci\u00f3n funcional a la fuerza p\u00fablica).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">2. Se empezar\u00e1 dialogo con las v\u00edctimas sobre:<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8211; Macrocaso 03 (ejecuciones extraudiciales).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8211; Macrocaso 04 (Urab\u00e1).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8211; Macrocaso 06 (V\u00edctimas UP).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8211; Macrocaso 08 (Crimines de fuerza p\u00fablica y paramilitares).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">3. Se levanta reserva sobre informaci\u00f3n de SALVATORE MANCUSO en audiencias reservadas.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">4. Existen otras solicitudes de ex paramilitares, la decisi\u00f3n tomada con MANCUSO crea expectativas (tienen pendiente su aceptaci\u00f3n MACACO, HEBERT VELOSA (HH) y HUGO AGUILAR Ex Gobernador de Santander) .<\/p>\n\n\n\n<p class=\"has-medium-font-size\">5. Compulsa de copias para investigaciones, fueron mencionadas m\u00e1s de 300 personas.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Y\u2026\u00bflas v\u00edctimas?<\/p>\n\n\n\n<p class=\"has-medium-font-size\">No han tenido participaci\u00f3n, han sido espectadores.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">La Magistrada Mar\u00eda del Pilar Valencia, en su salvamento de voto, expresa dos situaciones:<\/p>\n\n\n\n<p class=\"has-medium-font-size\">1. Fragmentaci\u00f3n de competencias.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">2. Las v\u00edctimas estar\u00edan avocadas a reclamar derechos ante diferentes autoridades (si es complicado desde la ley 1448 \u2013 SISTEMA DE REPARACI\u00d3N INTEGRAL DE V\u00cdCTIMAS y el SISTEMA INTEGRAL PARA LA PAZ del acuerdo final de 2016), ahora sumar JURISDICCI\u00d3N ESPECIAL PARA LA PAZ, CORTE SUPREMA DE JUSTICIA y JUSTICIA Y PAZ.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u00a1Qu\u00e9 enredo!, es de esperar que el sesgo pol\u00edtico no sea el que prime.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">EGU SUM QUESUM.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">(Todo sea por \u201cla paz total)<\/p>\n\n\n\n<ul class=\"wp-block-social-links has-visible-labels is-layout-flex wp-block-social-links-is-layout-flex\">\n\n\n\n\n\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por medio de la Res. 244 de 2023, el Presidente GUSTAVO PETRO, design\u00f3 a SALVATORE MANCUSO G\u00d3MEZ como gestor de paz, para que: \u201c\u2026contribuya con su conocimiento y experiencia al dise\u00f1o de procesos de desarme colectivos\u2026\u201d<br \/>\nEl gestor de paz queda bajo justicia y paz, la Jurisdicci\u00f3n Especial para la Paz y la Fiscal\u00eda General de la Naci\u00f3n. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"categories":[8,5],"tags":[42,41,40],"class_list":["post-696","post","type-post","status-publish","format-standard","hentry","category-derecho","category-rama-judicial","tag-gestor-de-paz","tag-jep","tag-mancuso"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts\/696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/comments?post=696"}],"version-history":[{"count":5,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts\/696\/revisions"}],"predecessor-version":[{"id":718,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/posts\/696\/revisions\/718"}],"wp:attachment":[{"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/media?parent=696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/categories?post=696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gabinetejuridico.co\/index.php\/wp-json\/wp\/v2\/tags?post=696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}